{"id":4189,"date":"2024-06-19T21:16:50","date_gmt":"2024-06-19T19:16:50","guid":{"rendered":"https:\/\/redestudiosafricanos.org\/?post_type=comunicacion&#038;p=4189"},"modified":"2024-10-07T11:27:58","modified_gmt":"2024-10-07T09:27:58","slug":"entre-canaverales-y-cacaotales-continuidades-y-resistencias-en-las-plantaciones-de-cuba-y-la-guinea-espanola-1860-1968","status":"publish","type":"comunicacion","link":"https:\/\/redestudiosafricanos.org\/ca\/comunicacion\/entre-canaverales-y-cacaotales-continuidades-y-resistencias-en-las-plantaciones-de-cuba-y-la-guinea-espanola-1860-1968\/","title":{"rendered":"Entre ca\u00f1averales y cacaotales: continuidades y resistencias en las plantaciones de Cuba y la Guinea Espa\u00f1ola (1860-1968)"},"content":{"rendered":"<p>Esta investigaci\u00f3n sostiene que la plantaci\u00f3n como estructura econ\u00f3mica no solo sobrevivi\u00f3 a la abolici\u00f3n, sino que tambi\u00e9n model\u00f3 las pol\u00edticas y sociedades contempor\u00e1neas, dejando un legado de racismo y explotaci\u00f3n que a\u00fan persiste. A la vez, propone que una forma de descolonizar la narrativa de la plantaci\u00f3n es el resaltar que estos espacios fueron no solo de producci\u00f3n econ\u00f3mica, sino tambi\u00e9n de afirmaci\u00f3n humana frente a la opresi\u00f3n, manteni\u00e9ndose vivos en las memorias colectivas de los pueblos de Cuba y Guinea Ecuatorial.<br \/>\nSe examinan los t\u00e9rminos legislativos de \u201cpatronato\u201d y \u201cemancipaci\u00f3n\u201d tanto en la era post abolicionista en Cuba (1879-1898), como en la Guinea Espa\u00f1ola (1900-1968), identificando similitudes en las pr\u00e1cticas coercitivas impuestas a los trabajadores en ambos lados del Atl\u00e1ntico, en los ingenios de Cuba y en las plantaciones de cacao y aceite de palma en Guinea Espa\u00f1ola. Se propone el t\u00e9rmino \u201cAntropoceno Hisp\u00e1nico\u201d para destacar c\u00f3mo el imperio espa\u00f1ol transform\u00f3 no solo los h\u00e1bitats naturales, sino tambi\u00e9n los socioculturales, imponiendo una l\u00f3gica de racializaci\u00f3n del cuerpo negro-africano como n\u00facleo de la pol\u00edtica y econom\u00eda colonial espa\u00f1ola en ambos lados del Atl\u00e1ntico.<br \/>\nLa metodolog\u00eda incluye el examen de documentos de la \u00e9poca, como leyes coloniales, narrativas abolicionistas y quejas escritas por esclavizados y trabajadores de los ingenios cubanos y plantaciones guineanas, con el objetivo de resaltar las formas de resistencia, incluyendo el cimarronaje, en ambos lados del Atl\u00e1ntico.<\/p>\n","protected":false},"author":43,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"ciea":[87],"class_list":["post-4189","comunicacion","type-comunicacion","status-publish","hentry","ciea-ciea12"],"acf":[],"_links":{"self":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/4189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion"}],"about":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/types\/comunicacion"}],"author":[{"embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/users\/43"}],"version-history":[{"count":1,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/4189\/revisions"}],"predecessor-version":[{"id":4190,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/4189\/revisions\/4190"}],"wp:attachment":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/media?parent=4189"}],"wp:term":[{"taxonomy":"ciea","embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/ciea?post=4189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}