{"id":6032,"date":"2024-09-04T10:12:13","date_gmt":"2024-09-04T08:12:13","guid":{"rendered":"https:\/\/redestudiosafricanos.org\/?post_type=comunicacion&#038;p=6032"},"modified":"2024-10-07T11:41:48","modified_gmt":"2024-10-07T09:41:48","slug":"desarticular-para-rearticular-una-multiculturalidad-sudafricana-posapartheid-30-anos-mas-tarde","status":"publish","type":"comunicacion","link":"https:\/\/redestudiosafricanos.org\/ca\/comunicacion\/desarticular-para-rearticular-una-multiculturalidad-sudafricana-posapartheid-30-anos-mas-tarde\/","title":{"rendered":"Desarticular para rearticular una multiculturalidad sudafricana posapartheid 30 a\u00f1os m\u00e1s tarde."},"content":{"rendered":"<p>Tras celebrar sus primeras elecciones multirraciales en 1994, la democracia que Sud\u00e1frica propon\u00eda para s\u00ed mismo era de unidad en la heterogeneidad. Sin embargo, tras pasar por el colonialismo, primero, y el apartheid, segundo, pues se hab\u00eda generado un orden nuevo y una sociedad que era, a todos los efectos, multi\u00e9tnico y multicultural, pero profundamente fragmentado. El Sud\u00e1frica postapartheid se enfrenta a dos retos importantes: desmontar el andamiaje colonialista, por un lado, y el segregacionista, por otro. Con todo, se estima necesario desarrollar una cultura democr\u00e1tica adem\u00e1s de implementar instituciones democr\u00e1ticas. Se pretende abordar lo anterior combinando lo mejor de la sabidur\u00eda de occidente con lo mejor de los conocimientos ind\u00edgenas africanos. Es en este terreno que puede iniciar la desarticulaci\u00f3n de un colonialismo interiorizado. Se presta, por tanto, como una posible referencia para las otras partes del mundo quienes se enfrenta a retos similares. Habiendo nacido una naci\u00f3n racializada, pretende trascender esta y las dem\u00e1s barreras no solo a trav\u00e9s de una pol\u00edtica de no racializaci\u00f3n sino abogando por la necesaria despolitizaci\u00f3n de una supuesta pertenencia racial. Se suma, por extensi\u00f3n, a las corrientes seg\u00fan las cuales resulta perjudicial en una sociedad racializar una nacionalidad si es que, al fin y al cabo, se desean entablar relaciones sociales equilibradas entre iguales. De esta manera es posible suplantar una hermen\u00e9utica racial con una intercultural, y, por ende, adoptar pr\u00e1cticas sociales e implementar pol\u00edticas equilibradas dirigidas al bien com\u00fan y a una convivencia ag\u00f3nica, pero civil. En fin, \u00bfC\u00f3mo se ve la unidad pol\u00edtica y la diversidad cultural en una democracia poscolonial y posapartheid 30 a\u00f1os m\u00e1s tarde? \u00bfQu\u00e9 lecciones se pueden extrapolar de esta experiencia?<\/p>\n","protected":false},"author":959,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"ciea":[87],"class_list":["post-6032","comunicacion","type-comunicacion","status-publish","hentry","ciea-ciea12"],"acf":[],"_links":{"self":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion"}],"about":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/types\/comunicacion"}],"author":[{"embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/users\/959"}],"version-history":[{"count":1,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6032\/revisions"}],"predecessor-version":[{"id":6033,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6032\/revisions\/6033"}],"wp:attachment":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/media?parent=6032"}],"wp:term":[{"taxonomy":"ciea","embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/ciea?post=6032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}