{"id":6263,"date":"2024-09-13T00:54:03","date_gmt":"2024-09-12T22:54:03","guid":{"rendered":"https:\/\/redestudiosafricanos.org\/?post_type=comunicacion&#038;p=6263"},"modified":"2024-10-09T11:57:04","modified_gmt":"2024-10-09T09:57:04","slug":"a-descolonizacao-e-localizacao-da-ajuda-ao-desenvolvimento-as-relacoes-de-poder-entre-ong-nacionais-e-internacionais-na-guine-bissau","status":"publish","type":"comunicacion","link":"https:\/\/redestudiosafricanos.org\/ca\/comunicacion\/a-descolonizacao-e-localizacao-da-ajuda-ao-desenvolvimento-as-relacoes-de-poder-entre-ong-nacionais-e-internacionais-na-guine-bissau\/","title":{"rendered":"A Descoloniza\u00e7\u00e3o e localiza\u00e7\u00e3o da Ajuda ao Desenvolvimento: As rela\u00e7\u00f5es de poder entre ONG Nacionais e Internacionais na Guin\u00e9-Bissau"},"content":{"rendered":"<p>A presen\u00e7a das ONG\u2019s na ajuda internacional ao desenvolvimento ganhou destaque com a ascens\u00e3o do neoliberalismo na d\u00e9cada de 1980. Inicialmente, a ajuda ao desenvolvimento era centralizada no Estado, atrav\u00e9s de programas setoriais (Sangreman, C., 2009). No entanto, o novo paradigma permitiu a participa\u00e7\u00e3o de atores n\u00e3o estatais, destacando as ONG\u2019s como intervenientes muitas vezes mais eficazes que os pr\u00f3prios Estados no apoio a popula\u00e7\u00f5es vulner\u00e1veis (Maranga, M. K., 2010; Kane, M., 2013).<br \/>\nApesar do seu papel reconhecido, a atua\u00e7\u00e3o das ONG\u2019s internacionais em pa\u00edses em desenvolvimento tem sido alvo de cr\u00edticas, principalmente por adotarem abordagens semelhantes \u00e0s dos Estados. Nestas abordagens, as prioridades s\u00e3o frequentemente definidas por atores externos, em detrimento das prioridades das autoridades e organiza\u00e7\u00f5es locais. As rela\u00e7\u00f5es entre ONG\u2019s nacionais e internacionais s\u00e3o marcadas por uma clara assimetria de poder, favorecendo as \u00faltimas. Este fen\u00f3meno \u00e9 particularmente evidente em pa\u00edses vulner\u00e1veis e politicamente inst\u00e1veis, como a Guin\u00e9-Bissau.<br \/>\nRecentemente, tem-se intensificado o debate sobre as rela\u00e7\u00f5es de poder desiguais entre ONG\u2019s internacionais e seus parceiros locais. Cresce a necessidade de promover abordagens de desenvolvimento mais enraizadas nos conhecimentos locais, dando maior protagonismo aos atores e organiza\u00e7\u00f5es nacionais, com vista a tornar os programas de desenvolvimento mais direcionados e adaptados \u00e0s realidades locais. Estes debates enquadram-se nas discuss\u00f5es em torno da descoloniza\u00e7\u00e3o e da localiza\u00e7\u00e3o da ajuda ao desenvolvimento.<br \/>\nPara promover mudan\u00e7as significativas nas abordagens, as ONG\u2019s internacionais apontam, sobretudo, a arquitetura da ajuda internacional como a principal barreira institucional \u00e0 transforma\u00e7\u00e3o (Banks, N. et al., 2024). Dada a relev\u00e2ncia deste debate, torna-se crucial investigar as barreiras que impedem avan\u00e7os na localiza\u00e7\u00e3o da ajuda, sendo a Guin\u00e9-Bissau o foco de estudo da investiga\u00e7\u00e3o que estamos a desenvolver.<\/p>\n","protected":false},"author":1181,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"ciea":[87],"class_list":["post-6263","comunicacion","type-comunicacion","status-publish","hentry","ciea-ciea12"],"acf":[],"_links":{"self":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion"}],"about":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/types\/comunicacion"}],"author":[{"embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/users\/1181"}],"version-history":[{"count":1,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6263\/revisions"}],"predecessor-version":[{"id":6264,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6263\/revisions\/6264"}],"wp:attachment":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/media?parent=6263"}],"wp:term":[{"taxonomy":"ciea","embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/ciea?post=6263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}