{"id":6423,"date":"2024-09-25T15:09:34","date_gmt":"2024-09-25T13:09:34","guid":{"rendered":"https:\/\/redestudiosafricanos.org\/?post_type=comunicacion&#038;p=6423"},"modified":"2024-10-07T11:42:06","modified_gmt":"2024-10-07T09:42:06","slug":"estetica-da-morte-e-transcendencia-em-choriro","status":"publish","type":"comunicacion","link":"https:\/\/redestudiosafricanos.org\/ca\/comunicacion\/estetica-da-morte-e-transcendencia-em-choriro\/","title":{"rendered":"Est\u00e9tica da Morte e Transcend\u00eancia em Choriro"},"content":{"rendered":"<p>No romance Choriro (2009) de Ungulani Ba Ka Khosa, a morte \u00e9 um processo de transforma\u00e7\u00e3o social, pol\u00edtica e espiritual, mais que um evento f\u00edsico. Nesta narrativa, ela ganha sentido simb\u00f3lico de continuidade e ruptura sociopol\u00edtica, passa a refletir um profundo elo com a ancestralidade e o poder no Vale do Zambeze. Neste trabalho, analiso Choriro \u00e0 luz da &quot;est\u00e9tica da morte&quot;, destacando como a obra a utiliza para narrar conflitos, din\u00e2micas  hist\u00f3ricas e sociopol\u00edticas da regi\u00e3o. Neste romance, h\u00e1 a recupera\u00e7\u00e3o de vozes marginalizadas que ajudam a reconstituir a hist\u00f3ria do Vale do Zambeze, a qual esteve frequentemente ofuscada pela narrativa da luta pela independ\u00eancia. A morte do mambo Nhabezi pode ser entendida como ruptura, pois inicia uma s\u00e9rie de rituais de luto e reflex\u00f5es pol\u00edticas, que perpassam valores africanos tradicionais e a realidade colonial; assim, ela se torna s\u00edmbolo da conex\u00e3o entre o espiritual e o pol\u00edtico, apresentando valorosos aspectos hist\u00f3ricos. O Choriro diz respeito \u00e0s cerim\u00f4nias de luto que, no caso do romance, s\u00e3o realizadas pelas seis esposas do mambo Nhabezi, cuja evoca\u00e7\u00e3o remete \u00e0 tradi\u00e7\u00e3o mpondoro, na qual, o falecido se transforma em esp\u00edrito protetor ancestral. Nesse momento, a transmuta\u00e7\u00e3o molda o futuro da comunidade, tamb\u00e9m simboliza a preserva\u00e7\u00e3o das identidades africanas frente ao colonialismo. Al\u00e9m disso, a morte em Choriro \u00e9 met\u00e1fora para a viol\u00eancia colonial e o impacto do tr\u00e1fico de escravos no s\u00e9culo XIX. Khosa retrata a viol\u00eancia f\u00edsica e simb\u00f3lica do Vale do Zambeze, articulando a morte como testemunho da destrui\u00e7\u00e3o causada pelo colonialismo e pela guerra, mas tamb\u00e9m como forma de resist\u00eancia e preserva\u00e7\u00e3o da mem\u00f3ria. Khosa revisita a hist\u00f3ria do Vale do Zambeze pela Literatura, o que enriquece a compreens\u00e3o dos processos sociopol\u00edticos mo\u00e7ambicanos sob novos \u00e2ngulos. O romance oferece uma reflex\u00e3o profunda sobre heran\u00e7as coloniais e caminhos de resist\u00eancia<\/p>\n","protected":false},"author":1264,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"ciea":[87],"class_list":["post-6423","comunicacion","type-comunicacion","status-publish","hentry","ciea-ciea12"],"acf":[],"_links":{"self":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion"}],"about":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/types\/comunicacion"}],"author":[{"embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/users\/1264"}],"version-history":[{"count":1,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6423\/revisions"}],"predecessor-version":[{"id":6424,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6423\/revisions\/6424"}],"wp:attachment":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/media?parent=6423"}],"wp:term":[{"taxonomy":"ciea","embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/ciea?post=6423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}