{"id":6596,"date":"2024-09-29T23:56:50","date_gmt":"2024-09-29T21:56:50","guid":{"rendered":"https:\/\/redestudiosafricanos.org\/?post_type=comunicacion&#038;p=6596"},"modified":"2024-10-06T20:14:35","modified_gmt":"2024-10-06T18:14:35","slug":"cantando-el-pasado-excavando-el-presente-dialogos-entre-arqueologia-y-tradicion-oral","status":"publish","type":"comunicacion","link":"https:\/\/redestudiosafricanos.org\/ca\/comunicacion\/cantando-el-pasado-excavando-el-presente-dialogos-entre-arqueologia-y-tradicion-oral\/","title":{"rendered":"Cantando el pasado, excavando el presente: di\u00e1logos entre arqueolog\u00eda y tradici\u00f3n oral."},"content":{"rendered":"<p>La arqueolog\u00eda ha hecho tradicionalmente un uso extractivo de las tradiciones orales, desde proyectos coloniales que las incorporaban de manera acr\u00edtica a interpretaciones m\u00e1s informadas y contextuales, pero casi siempre con un flujo unidireccional de la informaci\u00f3n. No s\u00f3lo eso, sino que en los casos en que la informaci\u00f3n ha fluido en sentido contrario (de la arqueolog\u00eda a la tradici\u00f3n), dicha transferencia ha sido lamentada como una &#039;contaminaci\u00f3n&#039; de la fuente original. Contrariamente a esta postura, considero que cualquier arqueolog\u00eda que se tome la deconolonizaci\u00f3n en serio debe no s\u00f3lo hacer uso de los saberes tradicionales, sino interaccionar productivamente con ellos. Como ejemplo, hablar\u00e9 del caso de  Kansala  \u00faltima capital del reino de Kaabu (s. XIII-XIX), en la actual Guinea-Bissau. Adem\u00e1s de ser un referente hist\u00f3rico, Kansala es tambi\u00e9n un hito musical, ligado al origen de la kora, s\u00edmbolo y principal herramienta de los griots.  Por ello, aprovechando la primera campa\u00f1a de excavaciones en Kansala, hemos desarrollado en colaboraci\u00f3n estrecha con griots locales varios mecanismos de co-creaci\u00f3n de informaci\u00f3n, cuyas dificultades y potencial explorar\u00e9 en esta presentaci\u00f3n.<\/p>\n","protected":false},"author":357,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"ciea":[87],"class_list":["post-6596","comunicacion","type-comunicacion","status-publish","hentry","ciea-ciea12"],"acf":[],"_links":{"self":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion"}],"about":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/types\/comunicacion"}],"author":[{"embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/users\/357"}],"version-history":[{"count":1,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6596\/revisions"}],"predecessor-version":[{"id":6597,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6596\/revisions\/6597"}],"wp:attachment":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/media?parent=6596"}],"wp:term":[{"taxonomy":"ciea","embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/ciea?post=6596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}