{"id":6741,"date":"2024-09-30T19:30:27","date_gmt":"2024-09-30T17:30:27","guid":{"rendered":"https:\/\/redestudiosafricanos.org\/?post_type=comunicacion&#038;p=6741"},"modified":"2024-10-07T18:26:13","modified_gmt":"2024-10-07T16:26:13","slug":"instabilidade-politica-democratica-e-a-oposicao-politica-na-guine-bissau","status":"publish","type":"comunicacion","link":"https:\/\/redestudiosafricanos.org\/ca\/comunicacion\/instabilidade-politica-democratica-e-a-oposicao-politica-na-guine-bissau\/","title":{"rendered":"Instabilidade Pol\u00edtica-democr\u00e1tica e a Oposi\u00e7\u00e3o Pol\u00edtica na Guin\u00e9-Bissau"},"content":{"rendered":"<p>A Guin\u00e9-Bissau, pa\u00eds da \u00c1frica Ocidental, tornou-se independente, em 1973, ap\u00f3s uma luta de liberta\u00e7\u00e3o nacional contra o colonialismo portugu\u00eas, que durou quase 11 anos, protagonizada pelo Partido Africano da Independ\u00eancia da Guin\u00e9 e Cabo-Verde (PAIGC) liderado por Am\u00edlcar Cabral. Ap\u00f3s a independ\u00eancia foi instaurado o regime autorit\u00e1rio de partido \u00fanico, que vigorou at\u00e9 \u00e0 data da abertura pol\u00edtica e implanta\u00e7\u00e3o do regime democr\u00e1tico com o multipartidarismo, em 1991. \u00c9 neste contexto, que surgiram muitos partidos pol\u00edticos legalmente constitu\u00eddos tirando hegemonia pol\u00edtica ao PAIGC, e, em 1994 realizaram-se as primeiras elei\u00e7\u00f5es legislativas e presidenciais simult\u00e2neas livres e democr\u00e1ticas. Foram eleitos o Presidente da Rep\u00fablica, por um mandato de 5 anos e os deputados da Assembleia Nacional Popular maioritariamente do PAIGC, por um mandato de 4 anos e formado o Governo. Antes de terminar o mandato dos \u00f3rg\u00e3os eleitos, a Guin\u00e9-Bissau viveu um conflito pol\u00edtico-militar entre 1998-1999, que op\u00f4s as For\u00e7as Armadas Revolucion\u00e1rias do Povo ao ent\u00e3o Presidente da Rep\u00fablica eleito, Jo\u00e3o Bernardo Vieira (Nino Vieira) e o seu Governo, que terminou com a derrota dos \u00f3rg\u00e3os do poder. A esta parte, seguiram-se outras altera\u00e7\u00f5es da ordem constitucional ora perpetradas por pol\u00edticos, ora por golpes de Estado militares. Paralelamente, foi crescendo o n\u00famero de partidos pol\u00edticos que j\u00e1 s\u00e3o mais de tr\u00eas dezenas, ao longo dos 33 anos de experi\u00eancia democr\u00e1tica na Guin\u00e9-Bissau. <br \/>\nNuma abordagem interdisciplinar com cruzamento das \u00e1reas disciplinares da ci\u00eancia pol\u00edtica, direito e sociologia, sobre esta tem\u00e1tica farei uma an\u00e1lise qualitativa para melhor compreender as causas da instabilidade, o retrocesso democr\u00e1tico e o papel dos partidos pol\u00edticos, em particular, os da oposi\u00e7\u00e3o. <\/p>\n<p>Palavras-chave: Guin\u00e9-Bissau, democracia, instabilidade pol\u00edtica, partidos pol\u00edticos<\/p>\n","protected":false},"author":1146,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"ciea":[87],"class_list":["post-6741","comunicacion","type-comunicacion","status-publish","hentry","ciea-ciea12"],"acf":[],"_links":{"self":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion"}],"about":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/types\/comunicacion"}],"author":[{"embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/users\/1146"}],"version-history":[{"count":1,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6741\/revisions"}],"predecessor-version":[{"id":6742,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6741\/revisions\/6742"}],"wp:attachment":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/media?parent=6741"}],"wp:term":[{"taxonomy":"ciea","embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/ciea?post=6741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}