{"id":6829,"date":"2024-10-01T03:52:50","date_gmt":"2024-10-01T01:52:50","guid":{"rendered":"https:\/\/redestudiosafricanos.org\/?post_type=comunicacion&#038;p=6829"},"modified":"2024-10-11T13:42:06","modified_gmt":"2024-10-11T11:42:06","slug":"insurgencias-no-teatro-afro-brasileiro-contemporaneo","status":"publish","type":"comunicacion","link":"https:\/\/redestudiosafricanos.org\/ca\/comunicacion\/insurgencias-no-teatro-afro-brasileiro-contemporaneo\/","title":{"rendered":"Insurg\u00eancias no teatro afro-brasileiro contempor\u00e2neo"},"content":{"rendered":"<p>Este estudo insere-se na perspectiva de analisar os processos de cria\u00e7\u00e3o e de escrita da dramaturgia no teatro afro-brasileiro contempor\u00e2neo, como tamb\u00e9m as tem\u00e1ticas insurgentes que trazem para o centro da cena a cruel realidade em que vive o povo negro no presente e no passado da hist\u00f3ria do Brasil. Toma como ponto de partida o livro &quot;Dramaturgia Negra&quot; (Funarte, 2018), a primeira antologia publicada no Brasil em que s\u00e3o reunidos textos teatrais escritos exclusivamente por autores afro-brasileiros de todas as regi\u00f5es do pa\u00eds, portanto um marco para a literatura dram\u00e1tica e para o teatro contempor\u00e2neo na Am\u00e9rica do Sul. Ser\u00e3o analisadas as formas de escrita e as inquieta\u00e7\u00f5es dramat\u00fargicas nas dezesseis obras que comp\u00f5em o livro, tecendo, assim, um verdadeiro panorama da dramaturgia contempor\u00e2nea no Brasil.<\/p>\n","protected":false},"author":1138,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"ciea":[87],"class_list":["post-6829","comunicacion","type-comunicacion","status-publish","hentry","ciea-ciea12"],"acf":[],"_links":{"self":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion"}],"about":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/types\/comunicacion"}],"author":[{"embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/users\/1138"}],"version-history":[{"count":1,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6829\/revisions"}],"predecessor-version":[{"id":6830,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/comunicacion\/6829\/revisions\/6830"}],"wp:attachment":[{"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/media?parent=6829"}],"wp:term":[{"taxonomy":"ciea","embeddable":true,"href":"https:\/\/redestudiosafricanos.org\/ca\/wp-json\/wp\/v2\/ciea?post=6829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}